{"id":116565,"date":"2021-06-27T13:59:19","date_gmt":"2021-06-27T11:59:19","guid":{"rendered":"https:\/\/www.il-libro.it\/?p=116565"},"modified":"2021-09-15T14:57:45","modified_gmt":"2021-09-15T12:57:45","slug":"rien-nest-noir-2","status":"publish","type":"post","link":"https:\/\/www.il-libro.it\/fr\/rien-nest-noir-2\/","title":{"rendered":"Rien n&rsquo;est noir"},"content":{"rendered":"<div class=\"separatore\">\n<p><img class=\"wp-image-116469 aligncenter\" src=\"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg\" alt=\"\" width=\"100\" height=\"162\" srcset=\"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg 269w, https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir-186x300.jpeg 186w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>\u00a0Rien n&rsquo;est noir<br \/>\n<\/strong> <\/em><\/p>\n<p style=\"text-align: center;\">de<\/p>\n<p style=\"text-align: center;\">Claire Berest<\/p>\n<p style=\"text-align: center;\"><strong>Mercredi, 6 Octobre 2021<\/strong><\/p>\n<p style=\"text-align: center;\">\n<strong>\u00e0 19h00<\/strong><\/p>\n<p style=\"text-align: center;\">avec la librairie il libro sur <strong>Zoom<\/strong>.<\/p>\n<p style=\"text-align: center;\">Pour vous inscrire envoyez nous un mail \u00e0 <a href=\"mailto:info@il-libro.it\" target=\"_blank\" rel=\"noopener\">info@il-libro.it<\/a> .<\/p>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\">Pour vous inscrire envoyez nous un mail \u00e0 <a href=\"mailto:info@il-libro.it?subject=iscrizione%20club%20di%20lettura%20di%20febbraio%20francese&amp;body=Buongiorno,%20vorrei%20partecipare%20all'incontro%20di%20francese%20di%febbraio\">info@il-libro.it<\/a> .<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>L\u2019auteure expose les passions, l\u2019art et les souffrances de la peintre fracass\u00e9e, cette magicienne des couleurs et pr\u00eatresse d\u2019une f\u00e9minit\u00e9 affranchie.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Le livre de Claire Berest est, d\u00e8s \u00e0 pr\u00e9sent, disponible chez votre libraire.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Rien n&rsquo;est noir de Claire Berest Mercredi, 6 Octobre 2021 \u00e0 19h00 avec la librairie il libro sur Zoom. Pour vous inscrire envoyez nous un mail \u00e0 info@il-libro.it . \u00a0 Pour vous inscrire envoyez nous un mail \u00e0 info@il-libro.it . &nbsp; L\u2019auteure expose les passions, l\u2019art et les souffrances de la peintre fracass\u00e9e, cette magicienne&hellip;<\/p>\n","protected":false},"author":5,"featured_media":116469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[295],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rien n&#039;est noir - Il Libro - Libreria Internazionale<\/title>\n<meta name=\"description\" content=\"Gruppo di lettura in francese con la libreria il libro di Milano. Prossimo appuntamento online ad ottobre &quot;Rien n&#039;est noir&quot; di Claire Berest.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.il-libro.it\/fr\/rien-nest-noir-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rien n&#039;est noir - Il Libro - Libreria Internazionale\" \/>\n<meta property=\"og:description\" content=\"Gruppo di lettura in francese con la libreria il libro di Milano. Prossimo appuntamento online ad ottobre &quot;Rien n&#039;est noir&quot; di Claire Berest.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Libro - Libreria Internazionale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IL-LIBRO-Libreria-Internazionale-2127680667458029\/?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-27T11:59:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-15T12:57:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"269\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.il-libro.it\/#organization\",\"name\":\"il libro libreria internazionale\",\"url\":\"https:\/\/www.il-libro.it\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/IL-LIBRO-Libreria-Internazionale-2127680667458029\/?fref=ts\",\"https:\/\/www.instagram.com\/il.libro.internazionale\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.il-libro.it\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.il-libro.it\/wp-content\/uploads\/2017\/03\/logo.png\",\"contentUrl\":\"https:\/\/www.il-libro.it\/wp-content\/uploads\/2017\/03\/logo.png\",\"width\":180,\"height\":90,\"caption\":\"il libro libreria internazionale\"},\"image\":{\"@id\":\"https:\/\/www.il-libro.it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.il-libro.it\/#website\",\"url\":\"https:\/\/www.il-libro.it\/\",\"name\":\"Il Libro - Libreria Internazionale\",\"description\":\"Benvenuti nella libreria internazionale\",\"publisher\":{\"@id\":\"https:\/\/www.il-libro.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.il-libro.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg\",\"contentUrl\":\"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg\",\"width\":269,\"height\":435},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#webpage\",\"url\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/\",\"name\":\"Rien n'est noir - Il Libro - Libreria Internazionale\",\"isPartOf\":{\"@id\":\"https:\/\/www.il-libro.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#primaryimage\"},\"datePublished\":\"2021-06-27T11:59:19+00:00\",\"dateModified\":\"2021-09-15T12:57:45+00:00\",\"description\":\"Gruppo di lettura in francese con la libreria il libro di Milano. Prossimo appuntamento online ad ottobre \\\"Rien n'est noir\\\" di Claire Berest.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.il-libro.it\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rien n&#8217;est noir\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.il-libro.it\/#\/schema\/person\/6a34e9b4cc72b2d269e1ae45dcb83083\"},\"headline\":\"Rien n&rsquo;est noir\",\"datePublished\":\"2021-06-27T11:59:19+00:00\",\"dateModified\":\"2021-09-15T12:57:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#webpage\"},\"wordCount\":83,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.il-libro.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg\",\"articleSection\":[\"Rencontre Litt\\u00e9raire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.il-libro.it\/#\/schema\/person\/6a34e9b4cc72b2d269e1ae45dcb83083\",\"name\":\"Anna\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.il-libro.it\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5446c35a665205777a696408926ad672?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5446c35a665205777a696408926ad672?s=96&d=mm&r=g\",\"caption\":\"Anna\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rien n'est noir - Il Libro - Libreria Internazionale","description":"Gruppo di lettura in francese con la libreria il libro di Milano. Prossimo appuntamento online ad ottobre \"Rien n'est noir\" di Claire Berest.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.il-libro.it\/fr\/rien-nest-noir-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Rien n'est noir - Il Libro - Libreria Internazionale","og_description":"Gruppo di lettura in francese con la libreria il libro di Milano. Prossimo appuntamento online ad ottobre \"Rien n'est noir\" di Claire Berest.","og_url":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/","og_site_name":"Il Libro - Libreria Internazionale","article_publisher":"https:\/\/www.facebook.com\/IL-LIBRO-Libreria-Internazionale-2127680667458029\/?fref=ts","article_published_time":"2021-06-27T11:59:19+00:00","article_modified_time":"2021-09-15T12:57:45+00:00","og_image":[{"width":269,"height":435,"url":"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg","path":"\/var\/www\/vhosts\/il-libro.it\/httpdocs\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg","size":"full","id":116469,"alt":"","pixels":117015,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Anna","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.il-libro.it\/#organization","name":"il libro libreria internazionale","url":"https:\/\/www.il-libro.it\/","sameAs":["https:\/\/www.facebook.com\/IL-LIBRO-Libreria-Internazionale-2127680667458029\/?fref=ts","https:\/\/www.instagram.com\/il.libro.internazionale\/"],"logo":{"@type":"ImageObject","@id":"https:\/\/www.il-libro.it\/#logo","inLanguage":"fr-FR","url":"https:\/\/www.il-libro.it\/wp-content\/uploads\/2017\/03\/logo.png","contentUrl":"https:\/\/www.il-libro.it\/wp-content\/uploads\/2017\/03\/logo.png","width":180,"height":90,"caption":"il libro libreria internazionale"},"image":{"@id":"https:\/\/www.il-libro.it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.il-libro.it\/#website","url":"https:\/\/www.il-libro.it\/","name":"Il Libro - Libreria Internazionale","description":"Benvenuti nella libreria internazionale","publisher":{"@id":"https:\/\/www.il-libro.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.il-libro.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg","contentUrl":"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg","width":269,"height":435},{"@type":"WebPage","@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#webpage","url":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/","name":"Rien n'est noir - Il Libro - Libreria Internazionale","isPartOf":{"@id":"https:\/\/www.il-libro.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#primaryimage"},"datePublished":"2021-06-27T11:59:19+00:00","dateModified":"2021-09-15T12:57:45+00:00","description":"Gruppo di lettura in francese con la libreria il libro di Milano. Prossimo appuntamento online ad ottobre \"Rien n'est noir\" di Claire Berest.","breadcrumb":{"@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.il-libro.it\/rien-nest-noir-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.il-libro.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Rien n&#8217;est noir"}]},{"@type":"Article","@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#article","isPartOf":{"@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#webpage"},"author":{"@id":"https:\/\/www.il-libro.it\/#\/schema\/person\/6a34e9b4cc72b2d269e1ae45dcb83083"},"headline":"Rien n&rsquo;est noir","datePublished":"2021-06-27T11:59:19+00:00","dateModified":"2021-09-15T12:57:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#webpage"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/www.il-libro.it\/#organization"},"image":{"@id":"https:\/\/www.il-libro.it\/rien-nest-noir-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.il-libro.it\/wp-content\/uploads\/2021\/06\/BerestRiennestnoir.jpeg","articleSection":["Rencontre Litt\u00e9raire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.il-libro.it\/rien-nest-noir-2\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.il-libro.it\/#\/schema\/person\/6a34e9b4cc72b2d269e1ae45dcb83083","name":"Anna","image":{"@type":"ImageObject","@id":"https:\/\/www.il-libro.it\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/5446c35a665205777a696408926ad672?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5446c35a665205777a696408926ad672?s=96&d=mm&r=g","caption":"Anna"}}]}},"_links":{"self":[{"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/posts\/116565"}],"collection":[{"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/comments?post=116565"}],"version-history":[{"count":3,"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/posts\/116565\/revisions"}],"predecessor-version":[{"id":116659,"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/posts\/116565\/revisions\/116659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/media\/116469"}],"wp:attachment":[{"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/media?parent=116565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/categories?post=116565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.il-libro.it\/fr\/wp-json\/wp\/v2\/tags?post=116565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}